{"id":8193,"date":"2015-04-19T09:49:55","date_gmt":"2015-04-19T07:49:55","guid":{"rendered":"http:\/\/www.anyssa.org\/classedesgnomes\/?p=8193"},"modified":"2019-09-30T20:39:47","modified_gmt":"2019-09-30T18:39:47","slug":"hda-les-mandalas-de-sable-tibetains","status":"publish","type":"post","link":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/","title":{"rendered":"HDA &#8211; Les mandalas de sable tib\u00e9tains"},"content":{"rendered":"<p><a title=\"mandala de sable kalachakra\" href=\"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie1200.png\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"illustration alignright\" title=\"kalachakra_mandala\" src=\"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?resize=200%2C201\" alt=\"kalachakra_mandala\" width=\"200\" height=\"201\"><\/a>Les rempla\u00e7ants, c&rsquo;est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu&rsquo;on leur pr\u00eate. Du coup, j&rsquo;ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m&rsquo;y suis tenue jusqu&rsquo;\u00e0 aujourd&rsquo;hui. Mais c&rsquo;\u00e9tait sans compter sur une titulaire qui inscrit l&rsquo;activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace&#8230;<\/p>\n<h2>La pr\u00e9sentation de la s\u00e9quence<\/h2>\n<p>J&rsquo;ai donc d\u00e9cid\u00e9 d&rsquo;\u00e9toffer l&rsquo;activit\u00e9 mandala en la reliant \u00e0 une oeuvre d&rsquo;art : les mandalas de sable des moines tib\u00e9tains. Apr\u00e8s quelques recherches, j&rsquo;ai \u00e9labor\u00e9 un diaporama pour d\u00e9couvrir ces dessins magnifiques, et j&rsquo;ai mont\u00e9 deux courtes vid\u00e9os dans lesquelles on voit les moines en action. La s\u00e9quence se cl\u00f4ture pour la lecture de la fiche d&rsquo;identit\u00e9 de l&rsquo;oeuvre. J&rsquo;ai aussi, tout de m\u00eame, compil\u00e9 une quinzaine de mandalas abstraits dans l&rsquo;esprit des mandalas de sable.<\/p>\n<h2>Le d\u00e9roulement de la s\u00e9quence<\/h2>\n<h3><a title=\"Mandala de sable\" href=\"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/Mandala-moines-tibetains-8.png\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"illustration alignright\" title=\"Mandala de sable\" src=\"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/Mandala-moines-tibetains-8-200.png?resize=200%2C198\" alt=\"Mandala de sable\" width=\"200\" height=\"198\"><\/a>S\u00e9ance 1<\/h3>\n<h4 style=\"padding-left: 30px\">1\/ Rappel collectif de ce qu&rsquo;est un mandala<\/h4>\n<p style=\"padding-left: 60px\">Je liste sur une affiche les invariants d&rsquo;un mandala : une forme circulaire (le plus souvent), des trac\u00e9s qui vont du centre vers l&rsquo;ext\u00e9rieur, des trac\u00e9s g\u00e9om\u00e9triques et des formes, des couleurs, et bien s\u00fbr la sym\u00e9trie.<\/p>\n<h4 style=\"padding-left: 30px\">2\/ Diffusion du diaporama<\/h4>\n<p style=\"padding-left: 60px\">Je r\u00e9ponds aux questions des \u00e9l\u00e8ves au fur et \u00e0 mesure du visionnage des diapositives. Fatalement \u00e9merge la question : pourquoi ils d\u00e9truisent le mandala \u00e0 la fin ? Je diff\u00e8re le d\u00e9bat \u00e0 la s\u00e9ance suivante.<\/p>\n<h3>S\u00e9ance 2<\/h3>\n<h4 style=\"padding-left: 30px\">1\/ Diffusion des deux vid\u00e9os<\/h4>\n<h4 style=\"padding-left: 30px\">2\/ D\u00e9bat sur la question de la destruction<\/h4>\n<p style=\"padding-left: 60px\">Les \u00e9l\u00e8ves ont fait \u00e9merger deux raisons :<\/p>\n<ol>\n<ol>\n<ol style=\"list-style-type: lower-alpha\">\n<li>Les moines pr\u00e9l\u00e8vent du sable de la Terre, ils le lui restituent apr\u00e8s. Id\u00e9e d&rsquo;\u00e9quilibre \u00e0 pr\u00e9server, de rendre \u00e0 la nature ce qu&rsquo;on lui a pris. (= vision \u00e9cologique du mandala)<\/li>\n<li>Les moines symbolisent que tout a une fin sur la Terre, que rien n&rsquo;est \u00e9ternel, leurs mandalas comme tout ce qui se trouve sur Terre, les hommes y compris. (= vision philosophique du mandala)<\/li>\n<\/ol>\n<\/ol>\n<\/ol>\n<h4 style=\"padding-left: 30px\">3\/ Choix et coloriage d&rsquo;un mandala<\/h4>\n<h2>Les documents \u00e0 t\u00e9l\u00e9charger<\/h2>\n<h3>Le diaporama pour pr\u00e9senter les mandalas de sable<\/h3>\n<p style=\"padding-left: 30px\"><a title=\"Mandalas de sable - diaporama\" href=\"\/classedesgnomes\/wp-content\/uploads\/documents\/arts\/histoire-des-arts\/mandalas-de-sable_diaporama.pdf\"><img decoding=\"async\" class=\"telechargement alignnone\" title=\"Mandalas de sable - diaporama\" src=\"\/classedesgnomes\/wp-content\/uploads\/documents\/arts\/histoire-des-arts\/mandalas-de-sable_diaporama.jpg\" alt=\"Mandalas de sable - diaporama\" width=\"250\" height=\"159\"><\/a><\/p>\n<h3>La fiche d&rsquo;identit\u00e9 de l&rsquo;oeuvre<\/h3>\n<p style=\"padding-left: 30px\"><a title=\"Mandalas de sable - fiche d'identit\u00e9\" href=\"\/classedesgnomes\/wp-content\/uploads\/documents\/arts\/histoire-des-arts\/mandalas-de-sable_fiche-identite.pdf\"><img decoding=\"async\" class=\"telechargement alignnone\" title=\"Mandalas de sable - fiche d'identit\u00e9\" src=\"\/classedesgnomes\/wp-content\/uploads\/documents\/arts\/histoire-des-arts\/mandalas-de-sable_fiche-identite.jpg\" alt=\"Mandalas de sable - fiche d'identit\u00e9\" width=\"250\" height=\"180\"><\/a><\/p>\n<h3>15 mod\u00e8les de mandalas<\/h3>\n<p style=\"padding-left: 30px\"><a title=\"Mandalas de sable - mod\u00e8les\" href=\"\/classedesgnomes\/wp-content\/uploads\/documents\/arts\/histoire-des-arts\/mandalas_15-modeles.pdf\"><img decoding=\"async\" class=\"telechargement alignnone\" title=\"Mandalas de sable - mod\u00e8les\" src=\"\/classedesgnomes\/wp-content\/uploads\/documents\/arts\/histoire-des-arts\/mandalas_15-modeles.jpg\" alt=\"Mandalas de sable - mod\u00e8les\" width=\"250\" height=\"188\"><\/a><\/p>\n<h2>Les vid\u00e9os<\/h2>\n<p>J&rsquo;ai r\u00e9alis\u00e9 le montage de deux courtes vid\u00e9os, pour illustrer en images les \u00e9tapes de la cr\u00e9ation du mandala qui ont \u00e9t\u00e9 pr\u00e9sent\u00e9es dans le diaporama.<\/p>\n<table style=\"width: 50%\">\n<tbody>\n<tr>\n<td style=\"width: 50%;vertical-align: top\">Cette vid\u00e9o pr\u00e9sente les diff\u00e9rentes \u00e9tapes de la cr\u00e9ation de l&rsquo;oeuvre, du tra\u00e7age des formes \u00e0 la destruction du mandala.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;vertical-align: top\">Cette vid\u00e9o met l&rsquo;accent sur l&rsquo;\u00e9tape de la cr\u00e9ation du mandala. On y voit le minutieux et lent travail des moines.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les rempla\u00e7ants, c&rsquo;est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu&rsquo;on leur pr\u00eate. Du coup, j&rsquo;ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m&rsquo;y suis tenue jusqu&rsquo;\u00e0 aujourd&rsquo;hui. Mais c&rsquo;\u00e9tait sans compter sur une titulaire qui inscrit l&rsquo;activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace&#8230;<a class=\"more-link\" href=\"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/\">        &#x2192;<\/a><\/p>\n","protected":false},"author":2,"featured_media":8195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1163,763],"tags":[1035,387],"class_list":["entry","author-anyssa","has-excerpt","post-8193","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arts-du-visuel","category-arts-visuels","tag-mandala","tag-oeuvres-dart"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HDA - Les mandalas de sable tib\u00e9tains ~ La Classe des gnomes<\/title>\n<meta name=\"description\" content=\"Les rempla\u00e7ants, c&#039;est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu&#039;on leur pr\u00eate. Du coup, j&#039;ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m&#039;y suis tenue jusqu&#039;\u00e0 aujourd&#039;hui. Mais c&#039;\u00e9tait sans compter sur une titulaire qui inscrit l&#039;activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HDA - Les mandalas de sable tib\u00e9tains ~ La Classe des gnomes\" \/>\n<meta property=\"og:description\" content=\"Les rempla\u00e7ants, c&#039;est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu&#039;on leur pr\u00eate. Du coup, j&#039;ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m&#039;y suis tenue jusqu&#039;\u00e0 aujourd&#039;hui. Mais c&#039;\u00e9tait sans compter sur une titulaire qui inscrit l&#039;activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/\" \/>\n<meta property=\"og:site_name\" content=\"La Classe des gnomes\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-19T07:49:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-30T18:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Anyssa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Anyssa_SE\" \/>\n<meta name=\"twitter:site\" content=\"@Anyssa_SE\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anyssa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/\"},\"author\":{\"name\":\"Anyssa\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#\\\/schema\\\/person\\\/239c912ae4cbab448627207cdde96371\"},\"headline\":\"HDA &#8211; Les mandalas de sable tib\u00e9tains\",\"datePublished\":\"2015-04-19T07:49:55+00:00\",\"dateModified\":\"2019-09-30T18:39:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/\"},\"wordCount\":496,\"commentCount\":17,\"publisher\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#\\\/schema\\\/person\\\/239c912ae4cbab448627207cdde96371\"},\"image\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1\",\"keywords\":[\"Mandala\",\"Oeuvres d'art\"],\"articleSection\":[\"Arts du visuel\",\"Arts visuels\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/\",\"url\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/\",\"name\":\"HDA - Les mandalas de sable tib\u00e9tains ~ La Classe des gnomes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1\",\"datePublished\":\"2015-04-19T07:49:55+00:00\",\"dateModified\":\"2019-09-30T18:39:47+00:00\",\"description\":\"Les rempla\u00e7ants, c'est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu'on leur pr\u00eate. Du coup, j'ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m'y suis tenue jusqu'\u00e0 aujourd'hui. Mais c'\u00e9tait sans compter sur une titulaire qui inscrit l'activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1\",\"width\":200,\"height\":201,\"caption\":\"kalachakra_mandala\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/hda-les-mandalas-de-sable-tibetains\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HDA &#8211; Les mandalas de sable tib\u00e9tains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#website\",\"url\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/\",\"name\":\"La Classe des gnomes\",\"description\":\"Des ressources pour la maternelle et l&#039;\u00e9l\u00e9mentaire\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#\\\/schema\\\/person\\\/239c912ae4cbab448627207cdde96371\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#\\\/schema\\\/person\\\/239c912ae4cbab448627207cdde96371\",\"name\":\"Anyssa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Anyssa\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HDA - Les mandalas de sable tib\u00e9tains ~ La Classe des gnomes","description":"Les rempla\u00e7ants, c'est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu'on leur pr\u00eate. Du coup, j'ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m'y suis tenue jusqu'\u00e0 aujourd'hui. Mais c'\u00e9tait sans compter sur une titulaire qui inscrit l'activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/","og_locale":"fr_FR","og_type":"article","og_title":"HDA - Les mandalas de sable tib\u00e9tains ~ La Classe des gnomes","og_description":"Les rempla\u00e7ants, c'est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu'on leur pr\u00eate. Du coup, j'ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m'y suis tenue jusqu'\u00e0 aujourd'hui. Mais c'\u00e9tait sans compter sur une titulaire qui inscrit l'activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace...","og_url":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/","og_site_name":"La Classe des gnomes","article_published_time":"2015-04-19T07:49:55+00:00","article_modified_time":"2019-09-30T18:39:47+00:00","og_image":[{"width":200,"height":201,"url":"https:\/\/i1.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1","type":"image\/png"}],"author":"Anyssa","twitter_card":"summary_large_image","twitter_creator":"@Anyssa_SE","twitter_site":"@Anyssa_SE","twitter_misc":{"\u00c9crit par":"Anyssa","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#article","isPartOf":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/"},"author":{"name":"Anyssa","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#\/schema\/person\/239c912ae4cbab448627207cdde96371"},"headline":"HDA &#8211; Les mandalas de sable tib\u00e9tains","datePublished":"2015-04-19T07:49:55+00:00","dateModified":"2019-09-30T18:39:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/"},"wordCount":496,"commentCount":17,"publisher":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#\/schema\/person\/239c912ae4cbab448627207cdde96371"},"image":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1","keywords":["Mandala","Oeuvres d'art"],"articleSection":["Arts du visuel","Arts visuels"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/","url":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/","name":"HDA - Les mandalas de sable tib\u00e9tains ~ La Classe des gnomes","isPartOf":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#primaryimage"},"image":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1","datePublished":"2015-04-19T07:49:55+00:00","dateModified":"2019-09-30T18:39:47+00:00","description":"Les rempla\u00e7ants, c'est bien connu, sont des adeptes du mandala, activit\u00e9 occupationnelle par excellence. Du moins est-ce la r\u00e9putation qu'on leur pr\u00eate. Du coup, j'ai d\u00e9cid\u00e9 de ne jamais proposer de mandala lors de mes remplacements, et je m'y suis tenue jusqu'\u00e0 aujourd'hui. Mais c'\u00e9tait sans compter sur une titulaire qui inscrit l'activit\u00e9 au programme de son cahier-journal le jour o\u00f9 je la remplace...","breadcrumb":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#primaryimage","url":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1","width":200,"height":201,"caption":"kalachakra_mandala"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/hda-les-mandalas-de-sable-tibetains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.anyssa.org\/classedesgnomes\/"},{"@type":"ListItem","position":2,"name":"HDA &#8211; Les mandalas de sable tib\u00e9tains"}]},{"@type":"WebSite","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#website","url":"https:\/\/www.anyssa.org\/classedesgnomes\/","name":"La Classe des gnomes","description":"Des ressources pour la maternelle et l&#039;\u00e9l\u00e9mentaire","publisher":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#\/schema\/person\/239c912ae4cbab448627207cdde96371"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anyssa.org\/classedesgnomes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#\/schema\/person\/239c912ae4cbab448627207cdde96371","name":"Anyssa","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1","url":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Anyssa"},"logo":{"@id":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1"},"sameAs":["http:\/\/www.anyssa.org\/classedesgnomes\/"]}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2015\/04\/kalachakra_mandala-copie200.png?fit=200%2C201&ssl=1","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4022,"url":"https:\/\/www.anyssa.org\/classedesgnomes\/halloween-nouveaux-documents\/","url_meta":{"origin":8193,"position":0},"title":"Halloween &#8211; nouveaux documents","author":"Anyssa","date":"15 octobre 2013","format":false,"excerpt":"J'ai enrichi mon stock d'activit\u00e9s pour Halloween : des fiches \"Je dessine\", pour dessiner \u00e9tape par \u00e9tape des personnages d'Halloween, une s\u00e9rie d'images s\u00e9quentielles sur le th\u00e8me de la fabrication d'une lanterne en citrouille.","rel":"","context":"Dans &quot;Arts visuels&quot;","block_context":{"text":"Arts visuels","link":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-humaniste\/arts\/arts-visuels\/"},"img":{"alt_text":"PoZie la sorci\u00e8re sur son balai","src":"\/classedesgnomes\/wp-content\/uploads\/documents\/lutins\/pozie-sorciere-balai.gif","width":350,"height":200},"classes":[]},{"id":12960,"url":"https:\/\/www.anyssa.org\/classedesgnomes\/tps-ps-livre-de-traces-que-fait-ma-main-2\/","url_meta":{"origin":8193,"position":1},"title":"TPS-PS &#8211; Livre de traces \u00ab\u00a0Que fait ma main ?\u00a0\u00bb","author":"Anyssa","date":"17 octobre 2018","format":false,"excerpt":"Un livre de traces pour des TPS-PS, adapt\u00e9 du po\u00e8me \"Que fait ma main ?\". Une s\u00e9quence qui m\u00eale langage oral et arts plastiques, et qui est finalis\u00e9e par un livre individuel \u00e0 rapporter \u00e0 la maison.","rel":"","context":"Dans &quot;Arts platiques&quot;","block_context":{"text":"Arts platiques","link":"https:\/\/www.anyssa.org\/classedesgnomes\/maternelle\/arts-platiques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2019\/10\/que-fait-ma-main_min.jpg?fit=400%2C300&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9577,"url":"https:\/\/www.anyssa.org\/classedesgnomes\/coloriage-de-nombres-meles\/","url_meta":{"origin":8193,"position":2},"title":"Coloriage de nombres m\u00eal\u00e9s","author":"Anyssa","date":"30 octobre 2015","format":false,"excerpt":"J'ai propos\u00e9 l'an dernier \u00e0 des \u00e9l\u00e8ves de GS-CP de r\u00e9aliser un coloriage de nombres m\u00eal\u00e9s, ou plut\u00f4t des coloriages puisqu'il s'agissait d'un livret avec autant de feuilles que de nombres, de 1 \u00e0 9. C'est une chouette activit\u00e9 \u00e0 r\u00e9aliser en autonomie, apr\u00e8s l'activit\u00e9 collective de d\u00e9couverte.","rel":"","context":"Dans &quot;Maths&quot;","block_context":{"text":"Maths","link":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/"},"img":{"alt_text":"PoZ jongle avec les chiffres","src":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2014\/08\/poz-jongleur-chiffres-sansfond200.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13360,"url":"https:\/\/www.anyssa.org\/classedesgnomes\/art-a-la-maison-detourner-les-objets-du-quotidien-a-la-maniere-de-domenic-bahmann\/","url_meta":{"origin":8193,"position":3},"title":"Art \u00e0 la maison &#8211; D\u00e9tourner les objets du quotidien \u00e0 la mani\u00e8re de Domenic Bahmann","author":"Anyssa","date":"25 mars 2020","format":false,"excerpt":"Une activit\u00e9 d'art visuel cycles 2 et 3 \u00e0 faire \u00e0 la maison : une cr\u00e9ation \u00e0 la mani\u00e8re de Domenic Bahmann.","rel":"","context":"Dans &quot;Arts visuels&quot;","block_context":{"text":"Arts visuels","link":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-humaniste\/arts\/arts-visuels\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2020\/03\/a-la-maniere-de-bahmann_min.jpg?fit=400%2C300&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14182,"url":"https:\/\/www.anyssa.org\/classedesgnomes\/maternelle-gs-alphabet-cursif-arts-visuels\/","url_meta":{"origin":8193,"position":4},"title":"Maternelle GS &#8211; Alphabet cursif et arts visuels","author":"Anyssa","date":"8 mars 2022","format":false,"excerpt":"L'alphabet \u00e0 l'encre noire et l'alphabet en poin\u00e7onnage : deux activit\u00e9s qui allient \u00e9criture et arts visuels, pour familiariser les \u00e9l\u00e8ves avec le trac\u00e9 des lettres cursives.","rel":"","context":"Dans &quot;Langage&quot;","block_context":{"text":"Langage","link":"https:\/\/www.anyssa.org\/classedesgnomes\/maternelle\/langage\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2022\/03\/alphabet-cursif-arts-visuels_min-art.jpg?fit=400%2C300&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10988,"url":"https:\/\/www.anyssa.org\/classedesgnomes\/explorer-le-monde-absorption\/","url_meta":{"origin":8193,"position":5},"title":"Le pouvoir absorbant du papier &#8211; Explorer le monde et composition plastique","author":"Anyssa","date":"3 f\u00e9vrier 2017","format":false,"excerpt":"Deux ateliers pour conjuguer les domaines \"explorer le monde de la mati\u00e8re\" et \"activit\u00e9 artistique\" et exp\u00e9rimenter le pouvoir absorbant du papier.","rel":"","context":"Dans &quot;Arts platiques&quot;","block_context":{"text":"Arts platiques","link":"https:\/\/www.anyssa.org\/classedesgnomes\/maternelle\/arts-platiques\/"},"img":{"alt_text":"Cr\u00e9ation plastique - Absorption d'encre sur buvard","src":"\/classedesgnomes\/wp-content\/uploads\/documents\/maternelle\/GS\/buvard-absorption_materiel-h300.jpg","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/posts\/8193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/comments?post=8193"}],"version-history":[{"count":0,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/posts\/8193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/media\/8195"}],"wp:attachment":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/media?parent=8193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/categories?post=8193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/tags?post=8193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}