{"id":1152,"count":5,"description":"","link":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/","name":"Le\u00e7on \u00e0 manipuler - Maths","slug":"lecon-a-manipuler-maths","taxonomy":"category","parent":529,"meta":{"template":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>~ La Classe des gnomes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"~ La Classe des gnomes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/\" \/>\n<meta property=\"og:site_name\" content=\"La Classe des gnomes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Anyssa_SE\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/culture-scientifique\\\/maths\\\/lecon-a-manipuler-maths\\\/\",\"url\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/culture-scientifique\\\/maths\\\/lecon-a-manipuler-maths\\\/\",\"name\":\"~ La Classe des gnomes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/culture-scientifique\\\/maths\\\/lecon-a-manipuler-maths\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/culture-scientifique\\\/maths\\\/lecon-a-manipuler-maths\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture scientifique\",\"item\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/culture-scientifique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maths\",\"item\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/culture-scientifique\\\/maths\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Le\u00e7on \u00e0 manipuler - Maths\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#website\",\"url\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/\",\"name\":\"La Classe des gnomes\",\"description\":\"Des ressources pour la maternelle et l&#039;\u00e9l\u00e9mentaire\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#\\\/schema\\\/person\\\/239c912ae4cbab448627207cdde96371\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/#\\\/schema\\\/person\\\/239c912ae4cbab448627207cdde96371\",\"name\":\"Anyssa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Anyssa\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.anyssa.org\\\/classedesgnomes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/www.anyssa.org\\\/classedesgnomes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"~ La Classe des gnomes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/","og_locale":"fr_FR","og_type":"article","og_title":"~ La Classe des gnomes","og_url":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/","og_site_name":"La Classe des gnomes","twitter_card":"summary_large_image","twitter_site":"@Anyssa_SE","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/","url":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/","name":"~ La Classe des gnomes","isPartOf":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#website"},"breadcrumb":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/lecon-a-manipuler-maths\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.anyssa.org\/classedesgnomes\/"},{"@type":"ListItem","position":2,"name":"Culture scientifique","item":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/"},{"@type":"ListItem","position":3,"name":"Maths","item":"https:\/\/www.anyssa.org\/classedesgnomes\/culture-scientifique\/maths\/"},{"@type":"ListItem","position":4,"name":"Le\u00e7on \u00e0 manipuler - Maths"}]},{"@type":"WebSite","@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#website","url":"https:\/\/www.anyssa.org\/classedesgnomes\/","name":"La Classe des gnomes","description":"Des ressources pour la maternelle et l&#039;\u00e9l\u00e9mentaire","publisher":{"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#\/schema\/person\/239c912ae4cbab448627207cdde96371"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anyssa.org\/classedesgnomes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.anyssa.org\/classedesgnomes\/#\/schema\/person\/239c912ae4cbab448627207cdde96371","name":"Anyssa","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1","url":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Anyssa"},"logo":{"@id":"https:\/\/i0.wp.com\/www.anyssa.org\/classedesgnomes\/wp-content\/uploads\/2018\/09\/cropped-lutine_1_C02.jpg?fit=512%2C512&ssl=1"},"sameAs":["http:\/\/www.anyssa.org\/classedesgnomes\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/categories\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/categories\/529"}],"wp:post_type":[{"href":"https:\/\/www.anyssa.org\/classedesgnomes\/wp-json\/wp\/v2\/posts?categories=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}